{"id":4,"count":9,"description":"","link":"https:\/\/www.jerseyjimmagic.com\/blog\/category\/magic-shows-for-children\/","name":"Magic Shows for Children","slug":"magic-shows-for-children","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.jerseyjimmagic.com\/blog\/wp-json\/wp\/v2\/categories\/4"}],"collection":[{"href":"https:\/\/www.jerseyjimmagic.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.jerseyjimmagic.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.jerseyjimmagic.com\/blog\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}